{"id":49379,"date":"2026-03-25T16:05:09","date_gmt":"2026-03-25T19:05:09","guid":{"rendered":"https:\/\/juacontecimentos.com.br\/site\/?p=49379"},"modified":"2026-03-25T16:09:15","modified_gmt":"2026-03-25T19:09:15","slug":"trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera","status":"publish","type":"post","link":"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/","title":{"rendered":"Trabalho que gera resultado: press\u00e3o pol\u00edtica por melhorias em Anhanguera"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49381\" src=\"https:\/\/juacontecimentos.com.br\/site\/wp-content\/uploads\/2026\/03\/Screenshot_2026-03-25-16-07-22-521_com.whatsapp.jpg\" alt=\"\" width=\"957\" height=\"527\" srcset=\"https:\/\/juacontecimentos.com.br\/site\/wp-content\/uploads\/2026\/03\/Screenshot_2026-03-25-16-07-22-521_com.whatsapp.jpg 957w, https:\/\/juacontecimentos.com.br\/site\/wp-content\/uploads\/2026\/03\/Screenshot_2026-03-25-16-07-22-521_com.whatsapp-300x165.jpg 300w, https:\/\/juacontecimentos.com.br\/site\/wp-content\/uploads\/2026\/03\/Screenshot_2026-03-25-16-07-22-521_com.whatsapp-768x423.jpg 768w\" sizes=\"auto, (max-width: 957px) 100vw, 957px\" \/><\/p>\n<p>Hoje 25 de mar\u00e7o, no in\u00edcio da sess\u00e3o plen\u00e1ria, o deputado Issy Quinan levou ao plen\u00e1rio um requerimento apresentado pelo vereador Lucas, com demandas consideradas priorit\u00e1rias para Anhanguera. A pauta apresentada destaca, entre as principais a\u00e7\u00f5es, a necessidade de uma opera\u00e7\u00e3o tapa-buraco na GO-305, estrada que liga a GO-305 \u00e0 GO-402 e d\u00e1 acesso \u00e0 BR-050. A iniciativa visa reduzir os problemas de desgaste e buracos que afetam a trafegabilidade, a seguran\u00e7a dos motoristas e a circula\u00e7\u00e3o de servi\u00e7os municipais.<\/p>\n<p>Outra frente anunciada \u00e9 a manuten\u00e7\u00e3o e a recupera\u00e7\u00e3o da \u00e1rea de preserva\u00e7\u00e3o do reservat\u00f3rio gerido pela Saneago. O objetivo \u00e9 assegurar a prote\u00e7\u00e3o ambiental, garantir a qualidade da \u00e1gua e evitar agravamentos em \u00e1reas de entorno que costumam sofrer com eros\u00f5es e ocupa\u00e7\u00f5es indevidas.<\/p>\n<p>As propostas foram apresentadas com o compromisso de ampliar a seguran\u00e7a, melhorar a infraestrutura local e, consequentemente, elevar a qualidade de vida da popula\u00e7\u00e3o. Os representantes destacaram a necessidade de a\u00e7\u00f5es r\u00e1pidas e eficientes, ressaltando que os recursos e parcerias precisam ser otimizados para gerar resultados concretos na cidade.<\/p>\n<p>\u201cSeguimos firmes, trabalhando e cobrando melhorias para Anhanguera\u201d, afirmam os dois representantes, reiterando o compromisso com um desenvolvimento mais s\u00f3lido e sustent\u00e1vel para a regi\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje 25 de mar\u00e7o, no in\u00edcio da sess\u00e3o plen\u00e1ria, o deputado Issy Quinan levou ao plen\u00e1rio um requerimento apresentado pelo vereador Lucas, com demandas consideradas priorit\u00e1rias para Anhanguera. A pauta apresentada destaca, entre as principais a\u00e7\u00f5es, a necessidade de uma opera\u00e7\u00e3o tapa-buraco na GO-305, estrada que liga a GO-305 \u00e0 GO-402 e d\u00e1 acesso \u00e0<\/p>\n","protected":false},"author":2,"featured_media":49381,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,22,26,23],"tags":[],"class_list":["post-49379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-catalao","category-destaque","category-goias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trabalho que gera resultado: press\u00e3o pol\u00edtica por melhorias em Anhanguera - Jornal Ultimos Acontecimentos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trabalho que gera resultado: press\u00e3o pol\u00edtica por melhorias em Anhanguera - Jornal Ultimos Acontecimentos\" \/>\n<meta property=\"og:description\" content=\"Hoje 25 de mar\u00e7o, no in\u00edcio da sess\u00e3o plen\u00e1ria, o deputado Issy Quinan levou ao plen\u00e1rio um requerimento apresentado pelo vereador Lucas, com demandas consideradas priorit\u00e1rias para Anhanguera. A pauta apresentada destaca, entre as principais a\u00e7\u00f5es, a necessidade de uma opera\u00e7\u00e3o tapa-buraco na GO-305, estrada que liga a GO-305 \u00e0 GO-402 e d\u00e1 acesso \u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Ultimos Acontecimentos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jultimosacontecimentos\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-25T19:05:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T19:09:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/juacontecimentos.com.br\/site\/wp-content\/uploads\/2026\/03\/Screenshot_2026-03-25-16-07-22-521_com.whatsapp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"957\" \/>\n\t<meta property=\"og:image:height\" content=\"527\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reginaldo Ribeiro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reginaldo Ribeiro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/\"},\"author\":{\"name\":\"Reginaldo Ribeiro\",\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/#\/schema\/person\/082a54e6d3fdd7a633291428521c9669\"},\"headline\":\"Trabalho que gera resultado: press\u00e3o pol\u00edtica por melhorias em Anhanguera\",\"datePublished\":\"2026-03-25T19:05:09+00:00\",\"dateModified\":\"2026-03-25T19:09:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/\"},\"wordCount\":231,\"publisher\":{\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/juacontecimentos.com.br\/site\/wp-content\/uploads\/2026\/03\/Screenshot_2026-03-25-16-07-22-521_com.whatsapp.jpg\",\"articleSection\":[\"Brasil\",\"Catal\u00e3o\",\"Destaque\",\"Goi\u00e1s\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/\",\"url\":\"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/\",\"name\":\"Trabalho que gera resultado: press\u00e3o pol\u00edtica por melhorias em Anhanguera - Jornal Ultimos Acontecimentos\",\"isPartOf\":{\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/juacontecimentos.com.br\/site\/wp-content\/uploads\/2026\/03\/Screenshot_2026-03-25-16-07-22-521_com.whatsapp.jpg\",\"datePublished\":\"2026-03-25T19:05:09+00:00\",\"dateModified\":\"2026-03-25T19:09:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/#primaryimage\",\"url\":\"https:\/\/juacontecimentos.com.br\/site\/wp-content\/uploads\/2026\/03\/Screenshot_2026-03-25-16-07-22-521_com.whatsapp.jpg\",\"contentUrl\":\"https:\/\/juacontecimentos.com.br\/site\/wp-content\/uploads\/2026\/03\/Screenshot_2026-03-25-16-07-22-521_com.whatsapp.jpg\",\"width\":957,\"height\":527},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/juacontecimentos.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trabalho que gera resultado: press\u00e3o pol\u00edtica por melhorias em Anhanguera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/#website\",\"url\":\"https:\/\/juacontecimentos.com.br\/site\/\",\"name\":\"Jornal Ultimos Acontecimentos\",\"description\":\"Catal\u00e3o e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/juacontecimentos.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/#organization\",\"name\":\"Jornal Ultimos Acontecimentos\",\"url\":\"https:\/\/juacontecimentos.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/juacontecimentos.com.br\/site\/wp-content\/uploads\/2023\/04\/Logo_Site.png\",\"contentUrl\":\"https:\/\/juacontecimentos.com.br\/site\/wp-content\/uploads\/2023\/04\/Logo_Site.png\",\"width\":2476,\"height\":530,\"caption\":\"Jornal Ultimos Acontecimentos\"},\"image\":{\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/jultimosacontecimentos\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/#\/schema\/person\/082a54e6d3fdd7a633291428521c9669\",\"name\":\"Reginaldo Ribeiro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/juacontecimentos.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5c16c6837c3490270a74d888c2a845728f06bdde1f8761de1de1d1d1ef82d12f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5c16c6837c3490270a74d888c2a845728f06bdde1f8761de1de1d1d1ef82d12f?s=96&d=mm&r=g\",\"caption\":\"Reginaldo Ribeiro\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trabalho que gera resultado: press\u00e3o pol\u00edtica por melhorias em Anhanguera - Jornal Ultimos Acontecimentos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/","og_locale":"pt_BR","og_type":"article","og_title":"Trabalho que gera resultado: press\u00e3o pol\u00edtica por melhorias em Anhanguera - Jornal Ultimos Acontecimentos","og_description":"Hoje 25 de mar\u00e7o, no in\u00edcio da sess\u00e3o plen\u00e1ria, o deputado Issy Quinan levou ao plen\u00e1rio um requerimento apresentado pelo vereador Lucas, com demandas consideradas priorit\u00e1rias para Anhanguera. A pauta apresentada destaca, entre as principais a\u00e7\u00f5es, a necessidade de uma opera\u00e7\u00e3o tapa-buraco na GO-305, estrada que liga a GO-305 \u00e0 GO-402 e d\u00e1 acesso \u00e0","og_url":"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/","og_site_name":"Jornal Ultimos Acontecimentos","article_publisher":"https:\/\/www.facebook.com\/jultimosacontecimentos\/","article_published_time":"2026-03-25T19:05:09+00:00","article_modified_time":"2026-03-25T19:09:15+00:00","og_image":[{"width":957,"height":527,"url":"https:\/\/juacontecimentos.com.br\/site\/wp-content\/uploads\/2026\/03\/Screenshot_2026-03-25-16-07-22-521_com.whatsapp.jpg","type":"image\/jpeg"}],"author":"Reginaldo Ribeiro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reginaldo Ribeiro","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/#article","isPartOf":{"@id":"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/"},"author":{"name":"Reginaldo Ribeiro","@id":"https:\/\/juacontecimentos.com.br\/site\/#\/schema\/person\/082a54e6d3fdd7a633291428521c9669"},"headline":"Trabalho que gera resultado: press\u00e3o pol\u00edtica por melhorias em Anhanguera","datePublished":"2026-03-25T19:05:09+00:00","dateModified":"2026-03-25T19:09:15+00:00","mainEntityOfPage":{"@id":"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/"},"wordCount":231,"publisher":{"@id":"https:\/\/juacontecimentos.com.br\/site\/#organization"},"image":{"@id":"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/#primaryimage"},"thumbnailUrl":"https:\/\/juacontecimentos.com.br\/site\/wp-content\/uploads\/2026\/03\/Screenshot_2026-03-25-16-07-22-521_com.whatsapp.jpg","articleSection":["Brasil","Catal\u00e3o","Destaque","Goi\u00e1s"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/","url":"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/","name":"Trabalho que gera resultado: press\u00e3o pol\u00edtica por melhorias em Anhanguera - Jornal Ultimos Acontecimentos","isPartOf":{"@id":"https:\/\/juacontecimentos.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/#primaryimage"},"image":{"@id":"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/#primaryimage"},"thumbnailUrl":"https:\/\/juacontecimentos.com.br\/site\/wp-content\/uploads\/2026\/03\/Screenshot_2026-03-25-16-07-22-521_com.whatsapp.jpg","datePublished":"2026-03-25T19:05:09+00:00","dateModified":"2026-03-25T19:09:15+00:00","breadcrumb":{"@id":"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/#primaryimage","url":"https:\/\/juacontecimentos.com.br\/site\/wp-content\/uploads\/2026\/03\/Screenshot_2026-03-25-16-07-22-521_com.whatsapp.jpg","contentUrl":"https:\/\/juacontecimentos.com.br\/site\/wp-content\/uploads\/2026\/03\/Screenshot_2026-03-25-16-07-22-521_com.whatsapp.jpg","width":957,"height":527},{"@type":"BreadcrumbList","@id":"https:\/\/juacontecimentos.com.br\/site\/trabalho-que-gera-resultado-pressao-politica-por-melhorias-em-anhanguera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/juacontecimentos.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Trabalho que gera resultado: press\u00e3o pol\u00edtica por melhorias em Anhanguera"}]},{"@type":"WebSite","@id":"https:\/\/juacontecimentos.com.br\/site\/#website","url":"https:\/\/juacontecimentos.com.br\/site\/","name":"Jornal Ultimos Acontecimentos","description":"Catal\u00e3o e regi\u00e3o","publisher":{"@id":"https:\/\/juacontecimentos.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/juacontecimentos.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/juacontecimentos.com.br\/site\/#organization","name":"Jornal Ultimos Acontecimentos","url":"https:\/\/juacontecimentos.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/juacontecimentos.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/juacontecimentos.com.br\/site\/wp-content\/uploads\/2023\/04\/Logo_Site.png","contentUrl":"https:\/\/juacontecimentos.com.br\/site\/wp-content\/uploads\/2023\/04\/Logo_Site.png","width":2476,"height":530,"caption":"Jornal Ultimos Acontecimentos"},"image":{"@id":"https:\/\/juacontecimentos.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jultimosacontecimentos\/"]},{"@type":"Person","@id":"https:\/\/juacontecimentos.com.br\/site\/#\/schema\/person\/082a54e6d3fdd7a633291428521c9669","name":"Reginaldo Ribeiro","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/juacontecimentos.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5c16c6837c3490270a74d888c2a845728f06bdde1f8761de1de1d1d1ef82d12f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c16c6837c3490270a74d888c2a845728f06bdde1f8761de1de1d1d1ef82d12f?s=96&d=mm&r=g","caption":"Reginaldo Ribeiro"}}]}},"_links":{"self":[{"href":"https:\/\/juacontecimentos.com.br\/site\/wp-json\/wp\/v2\/posts\/49379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/juacontecimentos.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/juacontecimentos.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/juacontecimentos.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/juacontecimentos.com.br\/site\/wp-json\/wp\/v2\/comments?post=49379"}],"version-history":[{"count":2,"href":"https:\/\/juacontecimentos.com.br\/site\/wp-json\/wp\/v2\/posts\/49379\/revisions"}],"predecessor-version":[{"id":49382,"href":"https:\/\/juacontecimentos.com.br\/site\/wp-json\/wp\/v2\/posts\/49379\/revisions\/49382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/juacontecimentos.com.br\/site\/wp-json\/wp\/v2\/media\/49381"}],"wp:attachment":[{"href":"https:\/\/juacontecimentos.com.br\/site\/wp-json\/wp\/v2\/media?parent=49379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/juacontecimentos.com.br\/site\/wp-json\/wp\/v2\/categories?post=49379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/juacontecimentos.com.br\/site\/wp-json\/wp\/v2\/tags?post=49379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}